{"id":806,"date":"2011-11-16T11:03:49","date_gmt":"2011-11-16T10:03:49","guid":{"rendered":"https:\/\/abcdr.guyader.pro\/?p=806"},"modified":"2018-04-07T23:59:43","modified_gmt":"2018-04-07T22:59:43","slug":"comment-ajouter-des-courbes-des-points-et-des-droites-sur-un-graphique-lines-pointsabline","status":"publish","type":"post","link":"https:\/\/thinkr.fr\/abcdr\/comment-ajouter-des-courbes-des-points-et-des-droites-sur-un-graphique-lines-pointsabline\/","title":{"rendered":"Comment ajouter des courbes, des points et des droites sur un graphique ? lines, points,abline"},"content":{"rendered":"<p>R permet de faire beaucoup de chose avec les graphiques mais il faut coder ce qu&rsquo;on veut faire. Nous allons voir ici comment ajouter des courbes, des points et des droites sur un plot.<\/p>\n<pre><code><br \/><br \/>#on cr\u00e9e des donn\u00e9es pour l'exemple<br \/><br \/> x&lt;-seq(0:100)<br \/>a&lt;-2<br \/>b&lt;-5<br \/><br \/>y1&lt;-a*x+b<br \/>y2&lt;-a*x^0.5+b<br \/>y3&lt;-a*x^0.3+b*x<br \/><br \/>ynoisy1&lt;-y1+rnorm(length(y1),sd=0.2*y1)<br \/>ynoisy2&lt;-y2+rnorm(length(y2),sd=0.2*y2)<br \/>ynoisy3&lt;-y3+rnorm(length(y3),sd=0.2*y3)<br \/><br \/>#\u00e9tape 1 on trace la fonction y1 avec un plot<br \/><br \/>plot(y1~x,type='l',col=\"green\",lwd=2,ylim=c(0,300))<br \/><br \/>#\u00e9tape 2 on veut ajouter les fonctions y2 et y3 sur le m\u00eame graphiques : on utilise lines<br \/><br \/>lines(y2~x,type='l',col=\"blue\",lwd=2)<br \/>lines(y3~x,type='l',col=\"purple\",lwd=2)<br \/><br \/>#\u00e9tape 3 on veut ajouter les nuages de point ynoisy1 2 et 3 sur le graphique: on utilise points<br \/><br \/>points(ynoisy1~x,pch=20,col=\"grey\")<br \/>points(ynoisy2~x,pch=20,col=\"black\")<br \/>points(ynoisy3~x,pch=22,col=\"black\")<br \/><br \/>#\u00e9tape 4 on veut ajouter une droite verticale pour x=50 : on utilise abline(v=) v pour vertical<br \/><br \/> abline(v=50,col=\"red\")<br \/><br \/>#\u00e9tape 5 on veut une droite horizontale \u00e0 y=150 : idem avec h =<br \/><br \/>abline(h=150,col=\"red\")<br \/><br \/>#\u00e9tape 6 on veut une droite d'\u00e9quation y= -2*x+300 : abline avec c(ordonn\u00e9e,pente)<br \/>abline(c(300,-2),col=\"black\") <br \/> <br \/><\/code><\/pre>\n<p>Notez que ce graphique est tr\u00e8s moche&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R permet de faire beaucoup de chose avec les graphiques mais il faut coder ce qu&rsquo;on veut faire. Nous allons voir ici comment ajouter des courbes, des points et des droites sur un plot. #on cr\u00e9e des donn\u00e9es pour l&rsquo;exemple x&lt;-seq(0:100)a&lt;-2b&lt;-5y1&lt;-a*x+by2&lt;-a*x^0.5+by3&lt;-a*x^0.3+b*xynoisy1&lt;-y1+rnorm(length(y1),sd=0.2*y1)ynoisy2&lt;-y2+rnorm(length(y2),sd=0.2*y2)ynoisy3&lt;-y3+rnorm(length(y3),sd=0.2*y3)#\u00e9tape 1 on trace la fonction y1 avec un plotplot(y1~x,type=&rsquo;l&rsquo;,col=\u00a0\u00bbgreen\u00a0\u00bb,lwd=2,ylim=c(0,300))#\u00e9tape 2 on veut ajouter les fonctions y2 et y3 sur le m\u00eame graphiques : on utilise lineslines(y2~x,type=&rsquo;l&rsquo;,col=\u00a0\u00bbblue\u00a0\u00bb,lwd=2)lines(y3~x,type=&rsquo;l&rsquo;,col=\u00a0\u00bbpurple\u00a0\u00bb,lwd=2)#\u00e9tape 3 on veut ajouter les nuages de point ynoisy1 2 et 3 sur le graphique: on utilise pointspoints(ynoisy1~x,pch=20,col=\u00a0\u00bbgrey\u00a0\u00bb)points(ynoisy2~x,pch=20,col=\u00a0\u00bbblack\u00a0\u00bb)points(ynoisy3~x,pch=22,col=\u00a0\u00bbblack\u00a0\u00bb)#\u00e9tape 4 on veut ajouter une droite verticale pour x=50 : on utilise abline(v=) v pour vertical abline(v=50,col=\u00a0\u00bbred\u00a0\u00bb)#\u00e9tape 5 on veut<a class=\"more-link\" href=\"https:\/\/thinkr.fr\/abcdr\/comment-ajouter-des-courbes-des-points-et-des-droites-sur-un-graphique-lines-pointsabline\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_399453572_399453572":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-melen","4":"post-806","6":"format-standard","7":"category-graphique"},"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9O7Sx-d0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/comments?post=806"}],"version-history":[{"count":2,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/806\/revisions"}],"predecessor-version":[{"id":4136,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/806\/revisions\/4136"}],"wp:attachment":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/media?parent=806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/categories?post=806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/tags?post=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}