{"id":3187,"date":"2015-07-23T14:13:16","date_gmt":"2015-07-23T13:13:16","guid":{"rendered":"https:\/\/abcdr.guyader.pro\/?p=3187"},"modified":"2018-04-08T00:02:21","modified_gmt":"2018-04-07T23:02:21","slug":"comment-construire-un-test-du-chi-deux-sur-r-chisq-test","status":"publish","type":"post","link":"https:\/\/thinkr.fr\/abcdr\/comment-construire-un-test-du-chi-deux-sur-r-chisq-test\/","title":{"rendered":"Comment faire un test du chi-deux sur R ? chisq.test"},"content":{"rendered":"<p>Le test du khi2 permet de tester l\u2019ind\u00e9pendance de deux variables pour cela nous calculons la valeur de la statistique \u00a0ainsi que la probabilit\u00e9 critique.<\/p>\n<p>\u00a0<\/p>\n<p>Pour pouvoir r\u00e9aliser ce test il est n\u00e9cessaire d\u2019avoir un \u00e9chantillonnage al\u00e9atoire dans chaque \u00e9chantillon et que chaque effectif th\u00e9orique soit sup\u00e9rieur ou \u00e9gal \u00e0 5.<\/p>\n<p>\u00a0<\/p>\n<p>Pour effectuer ce test nous utilisons la fonction\u00a0<b>chisq.test()<\/b>.<\/p>\n<p>\u00a0<\/p>\n<p>Exemple :<\/p>\n<p>Nous nous demandons si nombre de fumeurs d\u00e9pend de l&rsquo;\u00e2ge ou non, c\u2019est-\u00e0-dire\u00a0: l\u2019\u00e2ge influence t\u2019il la propension \u00e0 fumer?<\/p>\n<pre><code>\u00a0\n\nmat&lt;-matrix(c(15,10,15,20,10,10),3)\n\ndimnames(mat) &lt;- list(c(\"15-30\",\"31-45\",\"46-70\") ,c(\"oui\",\"non\"))\n\n\u00a0\n\nmat\n\n\u00a0\u00a0\u00a0\u00a0\u00a0 oui non\n\n15-30\u00a0 15\u00a0 20\n\n31-45\u00a0 10\u00a0 10\n\n46-70\u00a0 15\u00a0 10\n\n\u00a0\n\nchisq.test(mat)\n\n\u00a0\n\n# \u00a0 \u00a0 \u00a0 \u00a0Pearson's Chi-squared test\n\n\u00a0\n\n#data:\u00a0 mat\n\n#X-squared = 1.7143, df = 2, p-value = 0.4244\n\n<\/code><\/pre>\n<p>La p-value est sup\u00e9rieure \u00e0 0.05, nous ne pouvons donc pas consid\u00e9rer que les variables sont li\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le test du khi2 permet de tester l\u2019ind\u00e9pendance de deux variables pour cela nous calculons la valeur de la statistique \u00a0ainsi que la probabilit\u00e9 critique. \u00a0 Pour pouvoir r\u00e9aliser ce test il est n\u00e9cessaire d\u2019avoir un \u00e9chantillonnage al\u00e9atoire dans chaque \u00e9chantillon et que chaque effectif th\u00e9orique soit sup\u00e9rieur ou \u00e9gal \u00e0 5. \u00a0 Pour effectuer ce test nous utilisons la fonction\u00a0chisq.test(). \u00a0 Exemple : Nous nous demandons si nombre de fumeurs d\u00e9pend de l&rsquo;\u00e2ge ou non, c\u2019est-\u00e0-dire\u00a0: l\u2019\u00e2ge influence t\u2019il la propension \u00e0 fumer? \u00a0 mat&lt;-matrix(c(15,10,15,20,10,10),3) dimnames(mat) &lt;- list(c(\u00ab\u00a015-30&Prime;,\u00a0\u00bb31-45&Prime;,\u00a0\u00bb46-70\u00a0\u00bb) ,c(\u00ab\u00a0oui\u00a0\u00bb,\u00a0\u00bbnon\u00a0\u00bb)) \u00a0 mat \u00a0\u00a0\u00a0\u00a0\u00a0 oui non 15-30\u00a0 15\u00a0 20 31-45\u00a0 10\u00a0 10 46-70\u00a0 15\u00a0 10 \u00a0<a class=\"more-link\" href=\"https:\/\/thinkr.fr\/abcdr\/comment-construire-un-test-du-chi-deux-sur-r-chisq-test\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_399453572_399453572":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-helene","4":"post-3187","6":"format-standard","7":"category-test"},"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9O7Sx-Pp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/3187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/comments?post=3187"}],"version-history":[{"count":2,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/3187\/revisions"}],"predecessor-version":[{"id":4296,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/3187\/revisions\/4296"}],"wp:attachment":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/media?parent=3187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/categories?post=3187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/tags?post=3187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}