{"id":1775,"date":"2012-06-25T16:35:33","date_gmt":"2012-06-25T15:35:33","guid":{"rendered":"https:\/\/abcdr.guyader.pro\/?p=1775"},"modified":"2018-04-08T00:00:48","modified_gmt":"2018-04-07T23:00:48","slug":"comment-ajouter-une-fleche-a-un-graphique-arrows","status":"publish","type":"post","link":"https:\/\/thinkr.fr\/abcdr\/comment-ajouter-une-fleche-a-un-graphique-arrows\/","title":{"rendered":"Comment ajouter une fl\u00e8che \u00e0 un graphique ? : arrows"},"content":{"rendered":"<p>Il peut \u00eatre utile d&rsquo;ajouter des fl\u00e8ches \u00e0 vos graphiques R. La fonction arrows est l\u00e0 pour vous!<\/p>\n<p>Comme toujours commencez par regarder les arguments de la fonction : ?arrows<br \/>Les 4 premiers aruguments correspondent aux coordonn\u00e9es (vecteurs de coordonn\u00e9es pour plusieurs fl\u00e8ches) de d\u00e9but et de fin de la fl\u00e8che. N&rsquo;hesitez pas \u00e0 utiliser la fonction locator() pour vous aider \u00e0 trouver ces coordonn\u00e9es. Ensuite vous pouvez choisir o\u00f9 se trouve le bout de la fl\u00e8che avec l&rsquo;arguement code. Enfin comme pour les courbes vous pouvez modifier l&rsquo;\u00e9paisseur, la couleur et le type de trait avec lwd,col et lty. Voici un exemple<\/p>\n<pre><code><br \/><br \/> #coordonn\u00e9es des fleches 1<br \/>x0&lt;-c(20,20)<br \/>y0&lt;-c(80,20)<br \/>x1&lt;-c(80,80)<br \/>y1&lt;-c(80,20)<br \/><br \/># autre jeu de fl\u00e8che<br \/>a0&lt;-c(10,70)<br \/>b0&lt;-c(90,10)<br \/>a1&lt;-c(50,50)<br \/>b1&lt;-c(70,10)<br \/><br \/>#on choisit les couleurs et le type de trait<br \/>couleur&lt;-c(\"green\",\"blue\")<br \/>lt&lt;-c(1,3)<br \/><br \/><br \/>plot.new()<br \/>plot.window(xlim=c(0,100),ylim=c(0,100))<br \/>arrows(x0,y0,x1,y1,code=3,lwd=2)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 #code=3 pour une double fl\u00e8che<br \/>arrows(a0,b0,a1,b1,code=1,lty=lt,col=couleur,lwd=4)<br \/>box() <br \/><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Il peut \u00eatre utile d&rsquo;ajouter des fl\u00e8ches \u00e0 vos graphiques R. La fonction arrows est l\u00e0 pour vous! Comme toujours commencez par regarder les arguments de la fonction : ?arrowsLes 4 premiers aruguments correspondent aux coordonn\u00e9es (vecteurs de coordonn\u00e9es pour plusieurs fl\u00e8ches) de d\u00e9but et de fin de la fl\u00e8che. N&rsquo;hesitez pas \u00e0 utiliser la fonction locator() pour vous aider \u00e0 trouver ces coordonn\u00e9es. Ensuite vous pouvez choisir o\u00f9 se trouve le bout de la fl\u00e8che avec l&rsquo;arguement code. Enfin comme pour les courbes vous pouvez modifier l&rsquo;\u00e9paisseur, la couleur et le type de trait avec lwd,col et lty. Voici un exemple #coordonn\u00e9es des fleches<a class=\"more-link\" href=\"https:\/\/thinkr.fr\/abcdr\/comment-ajouter-une-fleche-a-un-graphique-arrows\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_399453572_399453572":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-melen","4":"post-1775","6":"format-standard","7":"category-graphique"},"acf":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9O7Sx-sD","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/1775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/comments?post=1775"}],"version-history":[{"count":2,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/1775\/revisions"}],"predecessor-version":[{"id":4212,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/posts\/1775\/revisions\/4212"}],"wp:attachment":[{"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/media?parent=1775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/categories?post=1775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thinkr.fr\/abcdr\/wp-json\/wp\/v2\/tags?post=1775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}